{"id":4220,"date":"2017-07-24T13:07:09","date_gmt":"2017-07-24T13:07:09","guid":{"rendered":"http:\/\/businesslounge-elementor.rtthemes.com\/?page_id=4220"},"modified":"2024-03-03T20:56:33","modified_gmt":"2024-03-03T20:56:33","slug":"contact-us","status":"publish","type":"page","link":"https:\/\/whc-eg.com\/index.php\/contact-us\/","title":{"rendered":"Contact Us"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4220\" class=\"elementor elementor-4220\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-gucuzos elementor-section-full_width elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle default-style\" data-id=\"gucuzos\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;rt_color_sets&quot;:&quot;default-style&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ytnseho\" data-id=\"ytnseho\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ngciroo elementor-section-boxed elementor-section-height-default elementor-section-height-default default-style\" data-id=\"ngciroo\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;rt_color_sets&quot;:&quot;default-style&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ekzsxub\" data-id=\"ekzsxub\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-kvtvupb elementor-widget elementor-widget-rt-heading\" data-id=\"kvtvupb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"rt-heading-wrapper\">\n\t\t\t\t\t\t<h4 class=\"rt-heading\" >Contact Info<\/h4>\n\t\t\t\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-lzesopi elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"lzesopi\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/maps.app.goo.gl\/97PyUfQzkR4YfYkV7\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fasrt-elementor-icon icon-basic_geolocalize\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b><span>27 Street 200, Degla Maadi, Cairo, Egypt<\/span><\/b><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/maps.app.goo.gl\/VcKW5qWPCEJQc47MA\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fasrt-elementor-icon icon-basic_geolocalize\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b><span>Building 9,Hitech Park, Xiaoshan District Hangzhou City, Zhejiang, China<\/span><\/b><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:+201222114065\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fasrt-elementor-icon icon-basic-smartphone\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><b><span>(+20) 1222 114 065 | (+20) 1111303929<\/span><\/b><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-thiehsy\" data-id=\"thiehsy\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-vcdcpcq elementor-widget elementor-widget-rt-heading\" data-id=\"vcdcpcq\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rt-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"rt-heading-wrapper\">\n\t\t\t\t\t\t<h4 class=\"rt-heading\" >Contact Form<\/h4>\n\t\t\t\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-idaylok elementor-widget elementor-widget-rt-contact-form\" data-id=\"idaylok\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rt-contact-form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<!-- contact form -->\n\t\t<div  class=\"contact_form  dynamic-class-475591\">\n\t\t<div class=\"clear\"><\/div><div class=\"result\"><\/div>\n\t\t\t<form action=\"#\" name=\"contact_form\" class=\"validate_form rt_form\" method=\"post\">\n\t\t\t\t<ul>\n\t\t\t\t\t<li class=\"form-input\"><input placeholder=\"Your Name: (*)\" id=\"name\" type=\"text\" name=\"name\" value=\"\" class=\"required\" \/> <\/li>\n\t\t\t\t\t<li class=\"form-input\"><input placeholder=\"Your Email: (*)\" id=\"email\" type=\"email\" name=\"email\" value=\"\" class=\"required email\" \/><\/li>\n\t\t\t\t\t<li class=\"form-input\"><textarea placeholder=\"Your Message: (*)\" id=\"message\" name=\"message\" rows=\"8\" cols=\"40\" class=\"required\"><\/textarea><\/li>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t<li class=\"security-question\">9 + 86 = <input id=\"math\" placeholder=\"?\" type=\"text\" name=\"math\" value=\"\" class=\"required\" \/><\/li>\n\t\t\t\t\t<li class=\"submit-button\">\n\t\t\t\t\t<input type=\"hidden\" name=\"your_email\" value=\"c3VwcG9ydEB3aGMtZWcuY29t\"><input type=\"hidden\" name=\"dynamic_class\" value=\"dynamic-class-475591\"><input type=\"hidden\" name=\"rt_form_data\" value=\"OTU=\"><input type=\"button\" class=\"button submit\" value=\"Send\"  \/><span class=\"loading\"><\/span>\n\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t<\/form>\n\t\t<\/div><div class=\"clear\"><\/div>\n\t\t<!-- \/contact form -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-nd9ttjt elementor-section-full_width elementor-section-height-default elementor-section-height-default default-style\" data-id=\"nd9ttjt\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;rt_color_sets&quot;:&quot;default-style&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-q73o38k\" data-id=\"q73o38k\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0j2pw5d elementor-widget elementor-widget-rt-google-maps\" data-id=\"0j2pw5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rt-google-maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"google_map_holder\" data-height=\"500\" data-scope=\"#map-334969\" data-bw=\"true\">\n\n\t\t\t<div id=\"map-334969\" class=\"google_map\"><\/div>\n\t\t\t<script type=\"text\/javascript\">\n\t\t\t \/* <![CDATA[ *\/ \n\t\t\t\t\/\/ Runs google maps\t\n\t\t\t\t\tjQuery(function() {\n\t\t\t\t\t\tjQuery(window).on(\"load\",function(){\n\t\t\t\t\t\t\tjQuery(\"#map-334969\").rt_maps([[\"WHC EGYPT\", 29.9533015, 31.2699875, 4,\"27 Street 200, Degla MaadiCairo, EGYPT\"],],17); \n\t\t\t\t\t\t});\t\n\t\t\t\t\t});\n\t\t\t\/* ]]> *\/\t\n\t\t\t<\/script>\n\n\t\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Contact Info 27 Street 200, Degla Maadi, Cairo, Egypt Building 9,Hitech Park, Xiaoshan District Hangzhou City, Zhejiang, China (+20) 1222 114 065 | (+20) 1111303929 Contact Form 9 + 41 =<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4220","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/whc-eg.com\/index.php\/wp-json\/wp\/v2\/pages\/4220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/whc-eg.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/whc-eg.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/whc-eg.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/whc-eg.com\/index.php\/wp-json\/wp\/v2\/comments?post=4220"}],"version-history":[{"count":24,"href":"https:\/\/whc-eg.com\/index.php\/wp-json\/wp\/v2\/pages\/4220\/revisions"}],"predecessor-version":[{"id":5179,"href":"https:\/\/whc-eg.com\/index.php\/wp-json\/wp\/v2\/pages\/4220\/revisions\/5179"}],"wp:attachment":[{"href":"https:\/\/whc-eg.com\/index.php\/wp-json\/wp\/v2\/media?parent=4220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}